{"id":10761,"date":"2020-09-14T12:55:54","date_gmt":"2020-09-14T12:55:54","guid":{"rendered":"https:\/\/higeacbd.com\/huiles\/systeme-endocannabinoide\/"},"modified":"2025-03-24T12:00:45","modified_gmt":"2025-03-24T12:00:45","slug":"systeme-endocannabinoide","status":"publish","type":"post","link":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide","title":{"rendered":"Syst\u00e8me endocannabino\u00efde"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero&#8221; _builder_version=&#8221;4.6.1&#8243; background_color=&#8221;rgba(255,255,255,0.65)&#8221; background_image=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/cannabinoide.jpg&#8221; background_blend=&#8221;soft-light&#8221; custom_padding=&#8221;3vw||1vw|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;Syst\u00e8me endocannabino\u00efde&#8221; _builder_version=&#8221;4.6.1&#8243; header_level=&#8221;h1&#8243; header_font=&#8221;|800|||||||&#8221; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.3em&#8221; body_font=&#8221;|800|||||||&#8221; body_text_color=&#8221;#000000&#8243; body_font_size=&#8221;20px&#8221; body_line_height=&#8221;1.6em&#8221; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#00a88d&#8221; button_border_width=&#8221;8px&#8221; button_border_color=&#8221;rgba(47,56,84,0)&#8221; button_border_radius=&#8221;60px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; background_layout=&#8221;light&#8221; animation_direction=&#8221;bottom&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;50px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; button_text_color_hover=&#8221;#ffffff&#8221; button_border_radius_hover=&#8221;66px&#8221; button_letter_spacing_hover=&#8221;1px&#8221; button_bg_color_hover=&#8221;rgba(47,56,84,0.9)&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;66px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;1px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(47,56,84,0.9)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]Qu\u2019est-ce que le <strong>syst\u00e8me endocannabino\u00efde et comment<\/strong> fonctionne-t-il?[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Products&#8221; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#f3f3f1&#8243; custom_padding=&#8221;20px||11px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.5.1&#8243; custom_padding=&#8221;8px||17px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.1&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.14.5&#8243; text_font=&#8221;|500|||||||&#8221; text_text_color=&#8221;#000000&#8243; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.4em&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||12px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>En 1988, lors d\u2019une  <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/2848184\/\" target=\"_blank\" rel=\"noopener noreferrer\">subventionn\u00e9s par le gouvernement am\u00e9ricain de St. Louis. \u00c9cole de m\u00e9decine de l\u2019Universit\u00e9 Louis<\/a>Allyn Howlett et William Devane ont d\u00e9termin\u00e9 que le cerveau des mammif\u00e8res poss\u00e8de certains <a href=\"https:\/\/higeacbd.com\/fr?p=86757\" title=\"Receptores cannabinoides\">r\u00e9cepteurs cannabino\u00efdes<\/a> (CB1R) qui r\u00e9agissent aux compos\u00e9s pr\u00e9sents dans les plantes de cannabis. En fait, ces r\u00e9cepteurs sont le type de neurotransmetteurs qui abonde le plus dans le cerveau.<\/p>\n<p>Cette d\u00e9couverte scientifique a stimul\u00e9 les investissements dans la recherche sur le potentiel du cannabis. En 1990, <a href=\"https:\/\/www.nature.com\/articles\/346561a0\" target=\"_blank\" rel=\"noopener noreferrer\">une \u00e9quipe scientifique dirig\u00e9e par Lisa Matsuda a r\u00e9ussi \u00e0 cartographier la s\u00e9quence d\u2019ADN d\u2019un<\/a> de ces r\u00e9cepteurs cannabino\u00efdes dans le cerveau. Les exp\u00e9riences ont \u00e9t\u00e9 men\u00e9es sur des souris g\u00e9n\u00e9tiquement modifi\u00e9es d\u00e9pourvues du r\u00e9cepteur coupl\u00e9 aux prot\u00e9ines G : en effet, le THC cannabidiol administr\u00e9 \u00e0 ces souris n&#8217;a eu aucun effet, prouvant que le THC active les <a href=\"https:\/\/higeacbd.com\/fr\/avantages\/leffet-de-la-cdb-sur-le-cerveau\" title=\"Efecto CBD cerebro\">r\u00e9cepteurs cannabino\u00efdes dans le cerveau<\/a>. Au cours de cette m\u00eame \u00e9tude, un autre r\u00e9cepteur cannabino\u00efde a \u00e9t\u00e9 identifi\u00e9 qui a \u00e9t\u00e9 bautized comme CB2R et est pr\u00e9sent dans diff\u00e9rents tissus \u00e0 travers notre corps pr\u00e9dominant dans le syst\u00e8me immunitaire et le syst\u00e8me nerveux.<\/p>\n<p>Avec plusieurs r\u00e9cepteurs cannabino\u00efdes CB1R et CB2R d\u00e9j\u00e0 identifi\u00e9s, il \u00e9tait clair que <strong>chez chaque mammif\u00e8re il existe un r\u00e9seau complexe de r\u00e9cepteurs cannabino\u00efdes qui r\u00e9agissent avec les <a href=\"https:\/\/higeacbd.com\/fr?p=86777\" title=\"Endocannabinoides qu\u00e9 son\">endocannabino\u00efdes<\/a><\/strong> produits naturellement dans notre corps. Il s&#8217;agit du syst\u00e8me endocannabino\u00efde et il est situ\u00e9 non seulement dans le syst\u00e8me nerveux et le cerveau mais aussi <a href=\"https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/Human-CB1-Receptor-Isoforms-present-in-Hepatocytes-and-%CE%B2-cells-are-Involved-in-Regulating-Metabolism.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">il existe des preuves scientifiques que les mammif\u00e8res poss\u00e8dent des r\u00e9cepteurs de cannabino\u00efdes dans d&#8217;autres tissus organiques tels que le foie et le pancr\u00e9as<\/a>.<\/p>\n<p>Dans cet article, nous parlerons du <strong>r\u00e9cepteur des cannabino\u00efdes <\/strong>et du <strong>syst\u00e8me endocannabino\u00efde<\/strong>. En fait, l&#8217;ECS est consid\u00e9r\u00e9 comme un syst\u00e8me de signalisation cellulaire complexe, qui a \u00e9t\u00e9 d\u00e9couvert au d\u00e9but des ann\u00e9es 1990 par des scientifiques qui faisaient des recherches sur le THC.<\/p>\n<p>Comme nous le savons, le THC est un cannabino\u00efde bien connu, puisqu&#8217;il s&#8217;agit d&#8217;un compos\u00e9 que l&#8217;on trouve dans le cannabis. Il est important de noter que les chercheurs tentent toujours de comprendre pleinement le syst\u00e8me endocannabino\u00efde ainsi que les <strong>r\u00e9cepteurs cannabino\u00efdes<\/strong>, y compris le r\u00e9cepteur cb1. Ce que l&#8217;on sait \u00e0 ce jour, c&#8217;est qu&#8217;elle joue un r\u00f4le fondamental dans la r\u00e9gulation d&#8217;un large \u00e9ventail de fonctions et de processus dans nos organismes, notamment<\/p>\n<ul>\n<li>\u00c9tat d&#8217;esprit<\/li>\n<li>Reproduction et fertilit\u00e9<\/li>\n<li>La qualit\u00e9 du sommeil<\/li>\n<li>App\u00e9tit<\/li>\n<li>M\u00e9moire<\/li>\n<\/ul>\n<p>Il est int\u00e9ressant de mentionner que le syst\u00e8me endocannabino\u00efde (ECS) existe et est actif dans notre corps, m\u00eame sans avoir besoin de consommer du cannabis. Nous vous en disons un peu plus ci-dessous sur ce syst\u00e8me et sur le fonctionnement des r\u00e9cepteurs.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Produits&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_module=&#8221;16824&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_shop type=&#8221;best_selling&#8221; posts_number=&#8221;8&#8243; show_pagination=&#8221;on&#8221; module_class=&#8221;custom-shop&#8221; _builder_version=&#8221;4.13.0&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_shop][et_pb_signup mailchimp_list=&#8221;higeacbd|5b4d14cf0e&#8221; first_name_field=&#8221;off&#8221; last_name_field=&#8221;off&#8221; title=&#8221;Abonnez-vous et b\u00e9n\u00e9ficiez d\u2019une r\u00e9duction de 10%&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.13.0&#8243; header_level=&#8221;h4&#8243; header_font=&#8221;|800|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.2em&#8221; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#00a88d&#8221; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; button_custom_padding=&#8221;18px|0px|18px|0px|true|true&#8221; button_custom_padding_tablet=&#8221;14px||14px||true|true&#8221; button_custom_padding_phone=&#8221;12px||12px||true|true&#8221; button_custom_padding_last_edited=&#8221;on|phone&#8221; background_layout=&#8221;light&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; button_text_size_tablet=&#8221;14px&#8221; button_text_size_phone=&#8221;12px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; box_shadow_style_button=&#8221;preset4&#8243; box_shadow_horizontal_button=&#8221;0px&#8221; box_shadow_vertical_button=&#8221;2px&#8221; box_shadow_color_button=&#8221;#00a88d&#8221; global_colors_info=&#8221;{}&#8221; button_text_color__hover=&#8221;#28221d&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color_button__hover=&#8221;#000000&#8243; box_shadow_color_button__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_signup][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f3f3f1&#8243; custom_padding=&#8221;14px||27px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;12px||13px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.2em&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-5px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Cela fait 30 ans que ces d\u00e9couvertes se sont termin\u00e9es et il y a encore beaucoup de questions \u00e0 r\u00e9soudre concernant le syst\u00e8me endocannabino\u00efde. D\u2019une part, la l\u00e9gislation en vigueur au cours des derni\u00e8res d\u00e9cennies a stigmatis\u00e9 le cannabis en raison de ses effets psychotropes et, par cons\u00e9quent, a ralenti les investissements dans les \u00e9tudes scientifiques connexes. Cependant, d\u2019autre part, les applications empiriques et les exp\u00e9riences de ces derni\u00e8res ann\u00e9es ont r\u00e9ussi \u00e0 briser ces barri\u00e8res afin que la science puisse <a title=\"Estudios cient\u00edficos sobre los beneficios del CBD\" href=\"https:\/\/higeacbd.com\/fr\/etudes-scientifiques-sur-les-avantages-de-la-cdb\">d\u00e9chiffrer pourquoi de tels effets positifs sont d\u00e9crits lors de la consommation de certains cannabino\u00efdes.<\/a> Le <a title=\"Crecimiento del mercado de aceites CBD\" href=\"https:\/\/higeacbd.com\/fr\/datos\/croissance-du-marche-du-petrole-cbd\">march\u00e9 des d\u00e9riv\u00e9s du<\/a> cannabis est en plein essor et devrait atteindre 22 milliards de dollars au cours des prochaines ann\u00e9es.<\/p>\n<p><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/10392859\/\" target=\"_blank\" rel=\"noopener noreferrer\">Les r\u00e9cepteurs cannabioides ont \u00e9t\u00e9 trouv\u00e9s dans le genre Hydra,<\/a>un organisme tr\u00e8s primitif, de sorte que les scientifiques sentent que <strong>le syst\u00e8me endocannabino\u00efde est plus de 500 millions d\u2019ann\u00e9es<\/strong> dans l\u2019histoire de l\u2019\u00e9volution.<\/p>\n<h2>Comment fonctionne le syst\u00e8me des endocannabino\u00efdes (ECS) ? R\u00e9cepteurs endocannabino\u00efdes<\/h2>\n<p>Le syst\u00e8me endocannabino\u00efde est compos\u00e9 de trois \u00e9l\u00e9ments centraux, qui sont : les <strong>endocannabino\u00efdes<\/strong>, les <strong>r\u00e9cepteurs<\/strong> <strong>cannabino\u00efdes<\/strong> et les <strong>enzymes<\/strong>. Voyons en d\u00e9tail en quoi consiste chacun de ces \u00e9l\u00e9ments.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;12px||13px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.13.1&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;|800|||||||&#8221; header_3_text_align=&#8221;center&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-5px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Endocannabino\u00efdes<\/h3>\n<p>Les endocannabino\u00efdes sont \u00e9galement connus sous le nom de cannabino\u00efdes endog\u00e8nes. Il s&#8217;agit essentiellement de mol\u00e9cules produites par notre corps, et qui sont tr\u00e8s similaires aux cannabino\u00efdes que l&#8217;on trouve dans le cannabis. \u00c0 ce jour, les chercheurs ont pu identifier deux endocannabino\u00efdes cl\u00e9s, qui sont<\/p>\n<ul>\n<li><a href=\"https:\/\/higeacbd.com\/fr\/donnees\/cbd-et-anandamide\" title=\"Anandamida\">Anandamide<\/a> (AEA)<\/li>\n<li>2-arachidonoylglyc\u00e9rol (2-AG)<\/li>\n<\/ul>\n<p>Ces deux mol\u00e9cules visent \u00e0 contribuer au maintien des fonctions internes de notre corps sans conflit. Une chose importante \u00e0 noter est que notre corps produit des endocannabino\u00efdes au fur et \u00e0 mesure de ses besoins. C&#8217;est pourquoi il est souvent tr\u00e8s difficile de d\u00e9terminer les niveaux typiques de chaque mol\u00e9cule.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;|800|||||||&#8221; header_3_text_align=&#8221;center&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-5px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>R\u00e9cepteurs endocannabino\u00efdes<\/h3>\n<p>Ces r\u00e9cepteurs sont \u00e9galement produits par notre corps. En fait, on les trouve partout dans notre corps. La fonction des r\u00e9cepteurs est de<strong> se lier avec les endocannabino\u00efdes pour signaler au syst\u00e8me endocannabino\u00efde d&#8217;agir<\/strong>. Dans ce cas, deux principaux r\u00e9cepteurs cannabino\u00efdes ont \u00e9t\u00e9 identifi\u00e9s :<\/p>\n<ul>\n<li>Le premier est le <strong>r\u00e9cepteur cb1<\/strong>, que l&#8217;on trouve notamment dans le syst\u00e8me nerveux central de notre organisme.<\/li>\n<li>Le second est le <strong>r\u00e9cepteur cb2<\/strong>, qui dans ce cas est situ\u00e9 principalement dans le <a href=\"https:\/\/higeacbd.com\/fr\/maladies\/tics-nerveux-et-cbd\" title=\"Tics nerviosos CBD\">syst\u00e8me nerveux<\/a> p\u00e9riph\u00e9rique de notre corps, plus pr\u00e9cis\u00e9ment dans les cellules immunitaires.<\/li>\n<\/ul>\n<p>Il convient de noter ici que les<strong> endocannabino\u00efdes peuvent se lier \u00e0 l&#8217;un ou l&#8217;autre de ces deux r\u00e9cepteurs cannabino\u00efdes<\/strong>. Toutefois, les effets qui en r\u00e9sultent d\u00e9pendent de l&#8217;endroit o\u00f9 se trouve le r\u00e9cepteur, ainsi que du type d&#8217;endocannabino\u00efde auquel il se lie.<\/p>\n<p>En d&#8217;autres termes, les endocannabino\u00efdes peuvent se lier aux r\u00e9cepteurs cannabino\u00efdes cb1 sur un nerf spinal, dans le but de soulager la douleur. Il est \u00e9galement possible que d&#8217;autres endocannabino\u00efdes puissent se lier aux r\u00e9cepteurs cannabino\u00efdes cb2 de vos cellules immunitaires pour indiquer que l&#8217;organisme est en proie \u00e0 une inflammation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;12px||13px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;|800|||||||&#8221; header_3_text_align=&#8221;center&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-5px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Enzymes<\/h3>\n<p>Quant aux enzymes, ce<strong> sont des mol\u00e9cules organiques responsables de la d\u00e9composition des endocannabino\u00efdes<\/strong>, une fois qu&#8217;elles ont rempli leur fonction. Dans le syst\u00e8me endocannabino\u00efde, deux types d&#8217;enzymes sont principalement responsables de cette t\u00e2che :<\/p>\n<ul>\n<li>L&#8217;enzyme amide hydrolase d&#8217;acide gras, qui d\u00e9compose l&#8217;anandamide (AEA).<\/li>\n<li>L&#8217;enzyme monoacylglyc\u00e9rol acide lipase, qui dans ce cas d\u00e9compose le 2-arachidonoylglyc\u00e9rol (2-AG).<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;|800|||||||&#8221; header_3_text_align=&#8221;center&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-5px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Agoniste inverse et antagoniste inverse<\/h3>\n<p>L&#8217;agoniste est un m\u00e9dicament qui a la capacit\u00e9 d&#8217;imiter les effets des neurotransmetteurs endog\u00e8nes. L&#8217;agoniste inverse, d&#8217;autre part, est \u00e9galement un m\u00e9dicament, mais dans ce cas, il produit l&#8217;action oppos\u00e9e \u00e0 celle de l&#8217;agoniste. C&#8217;est-\u00e0-dire qu&#8217;il produit les effets oppos\u00e9s d&#8217;un neurotransmetteur.<\/p>\n<p>Il faut \u00e9galement dire que les antagonistes sont ceux qui sont responsables du blocage des effets des agonistes, et des agonistes inverses.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Features&#8221; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#f3f3f1&#8243; custom_padding=&#8221;0px|0px|0px|0px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;Ligne CTA&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.5.1&#8243; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0px|0px|0px|0px&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/sistema-endocannabinoide.jpg&#8221; alt=&#8221;syst\u00e8me endocannabino\u00efde&#8221; title_text=&#8221;syst\u00e8me endocannabino\u00efde&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.6.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#00a88d&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;Le syst\u00e8me endocannabino\u00efde dans l\u2019ensemble&#8221; button_url=&#8221;#top&#8221; _builder_version=&#8221;4.6.1&#8243; header_font=&#8221;|800|||||||&#8221; header_text_color=&#8221;#ffffff&#8221; body_font=&#8221;Montserrat|500|||||||&#8221; body_text_color=&#8221;#ffffff&#8221; body_link_text_color=&#8221;#000000&#8243; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#2f3854&#8243; button_border_width=&#8221;10px&#8221; button_border_color=&#8221;rgba(47,56,84,0)&#8221; button_border_radius=&#8221;60px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; button_alignment=&#8221;left&#8221; text_orientation=&#8221;left&#8221; max_width=&#8221;580px&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;40px|60px|2px|60px||&#8221; button_text_color_hover=&#8221;#2f3854&#8243; button_border_radius_hover=&#8221;66px&#8221; button_letter_spacing_hover=&#8221;1px&#8221; button_bg_color_hover=&#8221;#ffffff&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#2f3854&#8243; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;66px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;1px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;#ffffff&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>Tous les humains et les mammif\u00e8res ont un syst\u00e8me endocannabino\u00efde. C\u2019est <strong>un r\u00e9seau de r\u00e9cepteurs et de neurotransmetteurs qui r\u00e9gule les r\u00e9actions physiologiques en r\u00e9ponse \u00e0 notre environnement<\/strong> et est pr\u00e9sent dans diff\u00e9rents organes de notre corps, mais surtout dans notre cerveau et \u00e0 travers notre syst\u00e8me nerveux. D\u2019une mani\u00e8re g\u00e9n\u00e9rale, nous pourrions dire que le syst\u00e8me endocannabino\u00efde <strong>est responsable de faire fonctionner tous les syst\u00e8mes harmonieusement dans notre corps pour maintenir l\u2019hom\u00e9ostasie.<\/strong> Il s\u2019agit d\u2019un syst\u00e8me de <strong>neurotransmission<\/strong> qui est compos\u00e9 d\u2019endocannabino\u00efdes, d\u2019enzymes qui aident \u00e0 les synth\u00e9tiser, et les r\u00e9cepteurs cannabino\u00efdes avec lesquels ils se connectent et activent.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f3f3f1&#8243; custom_padding=&#8221;14px||27px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;12px||13px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.6.1&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.2em&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-5px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Qu\u2019est-ce que les endocannabino\u00efdes?<\/h2>\n<p>Ils sont les cannabino\u00efdes que votre corps est capable de produire et <strong>d\u2019agir comme neuromodulateurs pr\u00e9synaptically pour synth\u00e9tiser ou lib\u00e9rer un neurotransmetteur dans la fente synaptique.<\/strong><\/p>\n<p>Jusqu\u2019\u00e0 pr\u00e9sent, deux endocannabino\u00efdes ont \u00e9t\u00e9 identifi\u00e9s:<\/p>\n<ul>\n<li><strong>Anandamide (AEA)<\/strong>: est un neurotransmetteur d\u00e9riv\u00e9 d\u2019un acide gras essentiel om\u00e9ga 6. Tout comme le glutamate, l\u2019adr\u00e9naline ou l\u2019arachydonoylethanolamide de dopamine (AEA) passe par le syst\u00e8me nerveux et obtient des neurones de communiquer les uns avec les autres. Son nom vient du sanskrit \u00ab&nbsp;ananda&nbsp;\u00bb qui signifie bonheur et paix parce qu\u2019il est responsable de d\u00e9tente et de rassurer. On le trouve dans certains aliments comme le cacao et dans certains poissons, oursins et \u0153ufs.<\/li>\n<li><strong>2-araquidonilglyc\u00e9rol (2-AG)<\/strong><\/li>\n<\/ul>\n<p>Bien que ces deux endocannabino\u00efdes n\u2019aient \u00e9t\u00e9 d\u00e9termin\u00e9s qu\u2019\u00e0 l\u2019heure actuelle, la probabilit\u00e9 que la liste augmente est tr\u00e8s \u00e9lev\u00e9e \u00e0 mesure que la science progresse dans le domaine. <strong>Les endocannabino\u00efdes sont faits de phospholipides membranaires,<\/strong>la plupart d\u2019entre eux sont la combinaison d\u2019un acide gras avec une amine si les combinaisons naturelles sont immenses puisque dans notre corps il ya de nombreux types diff\u00e9rents d\u2019acides gras et d\u2019amines pr\u00e9sents. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Feature&#8221; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#f3f3f1&#8243; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;40px||40px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.4.4&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.4.4&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/receptores-cannabinoides.jpg&#8221; alt=&#8221;r\u00e9cepteurs cannabino\u00efdes&#8221; title_text=&#8221;r\u00e9cepteurs cannabino\u00efdes&#8221; _builder_version=&#8221;4.6.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.4.4&#8243; custom_padding_tablet=&#8221;|20%|||false|false&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.6.1&#8243; header_2_font=&#8221;|800|||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;|||0%|false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Qu\u2019est-ce que les r\u00e9cepteurs cannabino\u00efdes?<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.6.1&#8243; text_font_size_tablet=&#8221;14px&#8221; text_font_size_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Ils sont r\u00e9pandus dans tout notre organisme et les endocannabino\u00efdes transmettent des signaux pour le syst\u00e8me endocannabino\u00efde d\u2019agir.<\/p>\n<p>Jusqu\u2019\u00e0 pr\u00e9sent, 2 <strong>r\u00e9cepteurs cannabino\u00efdes sont connus<\/strong>:<\/p>\n<ul>\n<li><strong>CB1R<\/strong>: Ce <strong>sont des r\u00e9cepteurs m\u00e9tabotropes<\/strong> qui pr\u00e9dominent dans le syst\u00e8me nerveux central, dans le cerveau humain (chez d\u2019autres mammif\u00e8res, les r\u00e9cepteurs CB1 sont situ\u00e9s dans d\u2019autres tissus de leurs organismes). Pendant les synapses neuronales, les r\u00e9cepteurs CB1 <strong>mod\u00e8rent la neurotransmission excessive<\/strong> lorsque les neurones s\u00e9cr\u00e8tent trop de produits chimiques. Les endocannabino\u00efdes agissent alors <strong>comme inhibiteurs de neurotransmetteur tels que le glutamate (neurotransmetteur excitant)<\/strong> pour r\u00e9tablir l\u2019\u00e9quilibre. Lorsqu\u2019un neurotransmetteur excitant est s\u00e9cr\u00e9t\u00e9 \u00e0 partir de la cellule presynaptique, le neurotransmetteur se connecte et active le r\u00e9cepteur dans le neurone post-synaptique. Cette stimulation provoque la synth\u00e8se et la lib\u00e9ration d\u2019endocannabino\u00efdes qui voyagent \u00e0 travers la synapse neuronale o\u00f9 ils se connectent aux r\u00e9cepteurs CB1 situ\u00e9s dans la membrane de la cellule presynaptique. Une fois activ\u00e9, le r\u00e9cepteur CB1 commence \u00e0 inhiber la lib\u00e9ration du neurotransmetteur stimulant (comme le glutamate) provoquant un effecteur de relaxation.<\/li>\n<li><strong>CB2R<\/strong>: Ces r\u00e9cepteurs cannabino\u00efdes se trouvent dans le syst\u00e8me nerveux p\u00e9riph\u00e9rique en particulier dans les cellules immunitaires et dans le tractus intestinal. Les endocannabino\u00efdes activent les r\u00e9cepteurs CB2 situ\u00e9s dans les membranes cellulaires. Une fois <strong>activ\u00e9s, les r\u00e9cepteurs CB2 provoquent des r\u00e9actions immunitaires qui d\u00e9pendent du type de cellule et de son environnement.<\/strong> L\u2019activation du r\u00e9cepteur CB2 inhibe la production de cytosines inflammatoires qui g\u00e9n\u00e8re, entre autres, un effet anti-inflammatoire.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f3f3f1&#8243; custom_padding=&#8221;14px||27px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;12px||13px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.2em&#8221; max_width=&#8221;80%&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-5px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Quelles sont les fonctions du syst\u00e8me endocannabino\u00efde ?<\/h2>\n<p>Comme mentionn\u00e9 au d\u00e9but, il n&#8217;est pas encore possible de d\u00e9terminer pr\u00e9cis\u00e9ment comment fonctionne le syst\u00e8me endocannabino\u00efde (ECS) ni quelles sont toutes ses fonctions. Malgr\u00e9 cela, <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5877694\/\" target=\"_blank\" rel=\"noopener\">une \u00e9tude publi\u00e9e en 2018<\/a> a \u00e9tabli un lien entre un tel syst\u00e8me et un certain nombre de processus de notre corps. Il s&#8217;agit notamment des \u00e9l\u00e9ments suivants :<\/p>\n<ul>\n<li>M\u00e9tabolisme<\/li>\n<li>Douleur chronique<\/li>\n<li>App\u00e9tit et digestion<\/li>\n<li>\u00c9tat d&#8217;esprit<\/li>\n<li>Inflammation et autres r\u00e9actions du syst\u00e8me immunitaire<\/li>\n<li>Contr\u00f4le des moteurs<\/li>\n<li>Apprentissage et m\u00e9moire<\/li>\n<li>Formation musculaire, remodelage osseux et croissance<\/li>\n<li>Fonctionnement du syst\u00e8me cardiovasculaire<\/li>\n<li>Le stress et les nerfs<\/li>\n<li>La fonction du syst\u00e8me de reproduction<\/li>\n<\/ul>\n<p>L&#8217;int\u00e9r\u00eat de ces fonctions et processus dans l&#8217;organisme est qu&#8217;ils <strong>contribuent tous \u00e0 l&#8217;hom\u00e9ostasie<\/strong>, qui permet \u00e0 l&#8217;organisme de maintenir une condition interne stable. En d&#8217;autres termes, si une condition externe, telle que la douleur due \u00e0 une blessure, perturbe l&#8217;hom\u00e9ostasie du corps, le syst\u00e8me endocannabino\u00efde est activ\u00e9 pour ramener le corps \u00e0 un fonctionnement normal.<\/p>\n<p>Par cons\u00e9quent, de nombreux scientifiques et chercheurs consid\u00e8rent que le r\u00f4le principal du syst\u00e8me endocannabino\u00efde est de maintenir l&#8217;hom\u00e9ostasie.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Features&#8221; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#f3f3f1&#8243; custom_padding=&#8221;0px|0px|0px|0px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;Ligne CTA&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.5.1&#8243; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0px|0px|0px|0px&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/anandamida.jpg&#8221; alt=&#8221;anandamide&#8221; title_text=&#8221;anandamide&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.6.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#00a88d&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;O\u00f9 sont pr\u00e9sents les r\u00e9cepteurs cannabino\u00efdes?&#8221; button_url=&#8221;#top&#8221; _builder_version=&#8221;4.6.1&#8243; header_font=&#8221;|800|||||||&#8221; header_text_color=&#8221;#ffffff&#8221; body_font=&#8221;Montserrat|500|||||||&#8221; body_text_color=&#8221;#ffffff&#8221; body_link_text_color=&#8221;#000000&#8243; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#2f3854&#8243; button_border_width=&#8221;10px&#8221; button_border_color=&#8221;rgba(47,56,84,0)&#8221; button_border_radius=&#8221;60px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; button_alignment=&#8221;left&#8221; text_orientation=&#8221;left&#8221; max_width=&#8221;580px&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;40px|60px|2px|60px||&#8221; button_text_color_hover=&#8221;#2f3854&#8243; button_border_radius_hover=&#8221;66px&#8221; button_letter_spacing_hover=&#8221;1px&#8221; button_bg_color_hover=&#8221;#ffffff&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#2f3854&#8243; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;66px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;1px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;#ffffff&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p><strong>CB1R<\/strong><\/p>\n<ul>\n<li>Cerveau<\/li>\n<li>Poumons<\/li>\n<li>Syst\u00e8me vasculaire<\/li>\n<li>Muscles<\/li>\n<li>Gastro-intestinal<\/li>\n<li>Organes reproducteurs<\/li>\n<\/ul>\n<p><strong>CB2R<\/strong><\/p>\n<ul>\n<li>Rate<\/li>\n<li>Os<\/li>\n<li>Peau<\/li>\n<\/ul>\n<p><strong>CB1R et CB2R<\/strong><\/p>\n<ul>\n<li>Syst\u00e8me immunitaire<\/li>\n<li>Foie<\/li>\n<li>Moelle osseuse<\/li>\n<li>Pancr\u00e9as<\/li>\n<\/ul>\n<p>Les endocannabino\u00efdes peuvent se connecter \u00e0 l\u2019un de ces r\u00e9cepteurs et leurs effets d\u00e9pendront de l\u2019endroit o\u00f9 se trouve le r\u00e9cepteur et du cannabino\u00efde qu\u2019il relie.<\/p>\n<p>Par exemple, il ya des cannabino\u00efdes qui ciblent les r\u00e9cepteurs CB1 sur un nerf spinal pour soulager la douleur. D\u2019autres endocannabino\u00efdes peuvent se connecter avec le r\u00e9cepteur CB2 dans les cellules immunitaires pour faire croire au corps qu\u2019il \u00e9prouve une inflammation, un signe d\u2019insuffisance immunitaire.<\/p>\n<p>Les endocannabino\u00efdes <strong>peuvent interagir non seulement avec les r\u00e9cepteurs cannabino\u00efdes, mais aussi avec les enzymes et les canaux ioniques.<\/strong> Par exemple, <strong>l\u2019anandamide active et d\u00e9sensibilise un canal ionique appel\u00e9 TRPV1, r\u00e9duisant ainsi la perception de la douleur.<\/strong><\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Feature&#8221; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#f3f3f1&#8243; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;21px||18px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.5.1&#8243; custom_margin=&#8221;|auto|-2px|auto||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.5.1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/receptores-de-los-neurotransmisores.jpg&#8221; alt=&#8221;r\u00e9cepteurs de neurotransmetteur&#8221; title_text=&#8221;r\u00e9cepteurs de neurotransmetteur&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.6.1&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; max_width_phone=&#8221;300px&#8221; max_width_last_edited=&#8221;off|tablet&#8221; custom_margin=&#8221;|||-30%|false|false&#8221; custom_margin_tablet=&#8221;|||-15%|false|false&#8221; custom_margin_phone=&#8221;|||-10%|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.4.4&#8243; custom_padding_tablet=&#8221;|20%|||false|false&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.6.1&#8243; header_2_font=&#8221;|800|||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;|||0%|false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Comment les endocannabino\u00efdes se d\u00e9composent-ils?<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.0&#8243; text_font_size_tablet=&#8221;14px&#8221; text_font_size_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Sa vie dans le corps est tr\u00e8s courte. Une fois qu\u2019ils ont effectu\u00e9 leur fonction, ce sont les enzymes qui sont responsables de leur d\u00e9composition:<\/p>\n<ul>\n<li>L\u2019hydrolasse qui d\u00e9compose l\u2019AEA<\/li>\n<li>Le monoaliglyc\u00e9rol qui d\u00e9compose 2-AG<\/li>\n<\/ul>\n<p>Les niveaux d\u2019endocannabino\u00efdes sont d\u00e9termin\u00e9s <strong>par l\u2019\u00e9quilibre de<\/strong> la synth\u00e8se et de la d\u00e9gradation de ces traitements de sorte que la plupart des traitements qui cherchent \u00e0 niveler les endocannabino\u00efdes dans l\u2019attaque du corps l\u2019un de ces deux processus.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Features&#8221; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#f3f3f1&#8243; custom_padding=&#8221;0px|0px|0px|0px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;Ligne CTA&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.5.1&#8243; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0px|0px|0px|0px&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/hendidura-sinaptica.jpg&#8221; alt=&#8221;fissure synaptique&#8221; title_text=&#8221;fissure synaptique&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.6.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#00a88d&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;Comment maintenir la sant\u00e9 de notre syst\u00e8me endocannabino\u00efde?&#8221; button_url=&#8221;#top&#8221; _builder_version=&#8221;4.6.6&#8243; header_font=&#8221;|800|||||||&#8221; header_text_color=&#8221;#ffffff&#8221; body_font=&#8221;Montserrat|500|||||||&#8221; body_text_color=&#8221;#ffffff&#8221; body_link_text_color=&#8221;#000000&#8243; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#2f3854&#8243; button_border_width=&#8221;10px&#8221; button_border_color=&#8221;rgba(47,56,84,0)&#8221; button_border_radius=&#8221;60px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; button_alignment=&#8221;left&#8221; text_orientation=&#8221;left&#8221; max_width=&#8221;580px&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;40px|60px|2px|60px||&#8221; button_text_color_hover=&#8221;#2f3854&#8243; button_border_radius_hover=&#8221;66px&#8221; button_letter_spacing_hover=&#8221;1px&#8221; button_bg_color_hover=&#8221;#ffffff&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#2f3854&#8243; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;66px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;1px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;#ffffff&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>Un manque d\u2019exercice, de surpoids et de stress peut affecter n\u00e9gativement l\u2019\u00e9quilibre de notre syst\u00e8me endocannabino\u00efde et, par cons\u00e9quent, <a href=\"https:\/\/higeacbd.com\/fr\/datos\/homeostasie\" title=\"Homeostasis CBD\">l\u2019hom\u00e9ostasie<\/a> de notre corps. Pour r\u00e9tablir l\u2019\u00e9quilibre dans notre corps, nous pouvons b\u00e9n\u00e9ficier de cannabino\u00efdes exog\u00e8nes, ceux qui ne sont pas produits par notre corps. Plus de 100 cannabino\u00efdes sont trouv\u00e9s dans la seule plante de cannabis, bien que la plupart sont en attente d\u2019\u00e9tude scientifique. Les cannabino\u00efdes dont nous savons d\u00e9j\u00e0 un peu plus gr\u00e2ce \u00e0 la science sont le CBD et le THC. Le CBD et le THC interagissent diff\u00e9remment avec les r\u00e9cepteurs cannabino\u00efdes et c\u2019est pourquoi le CBD n\u2019a pas d\u2019effets psychotropes. En retour, le CBD se connecte \u00e0 d\u2019autres cibles mol\u00e9culaires telles que les r\u00e9cepteurs, les enzymes et les canaux ioniques.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Feature&#8221; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#f3f3f1&#8243; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;21px||18px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.5.1&#8243; custom_margin=&#8221;|auto|-2px|auto||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.5.1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2021\/02\/thc-receptores-cannabinoides.jpg&#8221; alt=&#8221;r\u00e9cepteurs de cannabino\u00efdes thc&#8221; title_text=&#8221;R\u00e9cepteurs cannabino\u00efdes du THC&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.9.0&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; max_width_phone=&#8221;300px&#8221; max_width_last_edited=&#8221;off|tablet&#8221; custom_margin=&#8221;|||-30%|false|false&#8221; custom_margin_tablet=&#8221;|||-15%|false|false&#8221; custom_margin_phone=&#8221;|||-10%|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.4.4&#8243; custom_padding_tablet=&#8221;|20%|||false|false&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.9.0&#8243; header_2_font=&#8221;|800|||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;|||0%|false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Comment le THC interagit-il avec les r\u00e9cepteurs cannabino\u00efdes ?<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.0&#8243; text_font_size_tablet=&#8221;14px&#8221; text_font_size_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Le THC est bien connu pour \u00eatre l&#8217;un des principaux cannabino\u00efdes pr\u00e9sents dans le cannabis. Lorsque le t\u00e9trahydrocannabinol (THC) p\u00e9n\u00e8tre dans notre corps, il <strong>interagit directement avec le syst\u00e8me endocannabino\u00efde<\/strong>, car il se lie aux r\u00e9cepteurs des cannabino\u00efdes de la m\u00eame mani\u00e8re que les endocannabino\u00efdes.<\/p>\n<p>Son effet puissant est d\u00fb en partie au fait qu&#8217;il peut se lier aux r\u00e9cepteurs cannabino\u00efdes cb1 et cb2. Par cons\u00e9quent, le THC <strong>peut g\u00e9n\u00e9rer une grande vari\u00e9t\u00e9 d&#8217;effets sur notre corps et notre esprit<\/strong>, dont certains ne sont pas si souhaitables. C&#8217;est-\u00e0-dire que si, d&#8217;une part, elle peut nous aider \u00e0 r\u00e9duire la douleur et \u00e0 stimuler l&#8217;app\u00e9tit, d&#8217;autre part, elle peut provoquer de l&#8217;anxi\u00e9t\u00e9 et, dans certains cas, de la parano\u00efa.<\/p>\n<p>C&#8217;est pourquoi les scientifiques cherchent maintenant des moyens de produire des cannabino\u00efdes THC synth\u00e9tiques qui interagissent avec le syst\u00e8me endocannabino\u00efde, mais seulement de mani\u00e8re positive pour la sant\u00e9.<\/p>\n<p>Et bien que le syst\u00e8me endocannabino\u00efde joue un r\u00f4le important dans le maintien de la stabilit\u00e9 des processus internes de l&#8217;organisme, de nombreuses recherches sont encore n\u00e9cessaires pour mieux comprendre ses fonctions et ses avantages potentiels.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Feature&#8221; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#f3f3f1&#8243; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;21px||18px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.5.1&#8243; custom_margin=&#8221;|auto|-2px|auto||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.5.1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/cual-es-el-mejor-aceite-de-cbd.jpg&#8221; alt=&#8221;Cbd et syst\u00e8me endocannabino\u00efde&#8221; title_text=&#8221;Cbd et syst\u00e8me endocannabino\u00efde&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.6.1&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; max_width_phone=&#8221;300px&#8221; max_width_last_edited=&#8221;off|tablet&#8221; custom_margin=&#8221;|||-30%|false|false&#8221; custom_margin_tablet=&#8221;|||-15%|false|false&#8221; custom_margin_phone=&#8221;|||-10%|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.4.4&#8243; custom_padding_tablet=&#8221;|20%|||false|false&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.6.1&#8243; header_2_font=&#8221;|800|||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;|||0%|false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Comment le CBD affecte-t-il notre syst\u00e8me endocannabino\u00efde?<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.6.1&#8243; text_font_size_tablet=&#8221;14px&#8221; text_font_size_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]Cbd augmente les niveaux d\u2019endocannabino\u00efde d\u2019anandamide en inhibant sa r\u00e9ception et sa d\u00e9gradation. En cons\u00e9quence, il ya plus d\u2019anandamide disponible pour activer les r\u00e9cepteurs cannabino\u00efdes presynaptiques.<\/p>\n<p>Si vous voulez en savoir plus <a href=\"https:\/\/higeacbd.com\/fr\/avantages-de-la-cdb\" title=\"Avantages cbd\">sur les avantages de la<\/a> consommation de CBD, nous vous recommandons de lire notre article connexe.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Art\u00edculos relacionados blog&#8221; _builder_version=&#8221;4.7.0&#8243; background_color=&#8221;#f3f3f1&#8243; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;21px||9px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.5.1&#8243; custom_margin=&#8221;|auto|-2px|auto||&#8221; custom_padding=&#8221;11px||7px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.5.1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.7.0&#8243; header_2_font=&#8221;|800|||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;|800|||||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_font_size=&#8221;45px&#8221; custom_margin=&#8221;||6px||false|false&#8221; custom_margin_tablet=&#8221;|||0%|false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;off|desktop&#8221; header_4_font_size_tablet=&#8221;40px&#8221; header_4_font_size_phone=&#8221;25px&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Articles connexes<\/h4>\n<p>[\/et_pb_text][et_pb_blog fullwidth=&#8221;off&#8221; posts_number=&#8221;6&#8243; include_categories=&#8221;current&#8221; show_more=&#8221;on&#8221; show_author=&#8221;off&#8221; show_date=&#8221;off&#8221; _builder_version=&#8221;4.7.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Subscribe&#8221; _builder_version=&#8221;4.5.1&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#f3f3f1&#8243; background_color_gradient_end=&#8221;rgba(255,255,255,0)&#8221; background_color_gradient_end_position=&#8221;30%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/aceite-de-cannabis-cbd.jpg&#8221; custom_padding=&#8221;100px|0px|30vw|0px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_duration=&#8221;1250ms&#8221; animation_intensity_slide=&#8221;1%&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.5.1&#8243; text_font=&#8221;|500|||||||&#8221; text_text_color=&#8221;rgba(47,56,84,0.5)&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.9em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|700|||||||&#8221; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Abonnez-vous \u00e0 notre newsletter<\/h2>\n<p>Abonnez-vous et b\u00e9n\u00e9ficiez d\u2019une r\u00e9duction de 10% sur votre achat.  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_2,1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;19px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_signup mailchimp_list=&#8221;higeacbd|5b4d14cf0e&#8221; first_name_field=&#8221;off&#8221; last_name_field=&#8221;off&#8221; _builder_version=&#8221;4.5.1&#8243; header_font=&#8221;||||||||&#8221; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#00a88d&#8221; button_border_width=&#8221;10px&#8221; button_border_color=&#8221;rgba(47,56,84,0)&#8221; button_border_radius=&#8221;89px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; border_radii_fields=&#8221;on|30px|30px|30px|30px&#8221; border_width_all_fields=&#8221;1px&#8221; border_color_all_fields=&#8221;rgba(47,56,84,0.2)&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_signup][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Footer&#8221; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#f3f3f1&#8243; background_image=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/cannabis-medicinal.jpg&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;bottom_center&#8221; global_module=&#8221;452&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.5.1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#000000&#8243; custom_padding=&#8221;4%|5%|4%|4%|true|false&#8221; custom_padding_tablet=&#8221;50px|30px|50px|30px|true|true&#8221; custom_padding_phone=&#8221;30px|20px|30px|20px|true|true&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.5.1&#8243; text_font=&#8221;Montserrat|800|||||||&#8221; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.2em&#8221; link_text_color=&#8221;#000000&#8243; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;#96bf00&#8243; header_3_font_size=&#8221;16px&#8221; header_3_letter_spacing=&#8221;2px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_4_font=&#8221;|700||on|||||&#8221; header_4_text_color=&#8221;#00a88d&#8221; header_4_font_size=&#8221;14px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;10px||10px||true|false&#8221; text_font_size_tablet=&#8221;22px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;14px&#8221; header_3_font_size_phone=&#8221;12px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>boutique<\/h4>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/spice-shop-32-1-1.png&#8221; alt=&#8221;simboolo higea&#8221; title_text=&#8221;simboolo higea&#8221; _builder_version=&#8221;4.5.1&#8243; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/higeacbd.com\/en\/tienda\/huiles\/oil-cbd-5\" title=\"Huile CBD 5%\">CBD \u00e0 5%<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"https:\/\/higeacbd.com\/en\/tienda\/huiles\/oil-cbd-10\" title=\"Aceite CBD 10%\">CBD \u00e0 10%<\/a>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/higeacbd.com\/en\/tienda\/huiles\/oil-cbd-20\" title=\"Huile CBD 20%\">CBD \u00e0 20%<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"https:\/\/higeacbd.com\/en\/tienda\/huiles\/oil-cbd-30\" title=\"Aceite CBD 30%\">CBD \u00e0 30%<\/a>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.1&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/higeacbd.com\/en\/tienda\/cremes-fr\/healing-balm-hygea-cbd\" title=\"Healing balm\">Baume cicatrisant<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.1&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/higeacbd.com\/en\/tienda\/cremes-fr\/muscle-pain-cream\" title=\"Crema dolor muscular\">Crema dolor muscular<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.1&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/higeacbd.com\/en\/tienda\/cremes-fr\/hygea-cbd-hand-cream\" title=\"Crema manos\">Cr\u00e8me pour les mains<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.1&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/higeacbd.com\/en\/tienda\/cremes-fr\/night-cream\" title=\"Crema facial\">Cr\u00e8me de nuit<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_button button_url=&#8221;https:\/\/higeacbd.com\/tienda&#8221; button_text=&#8221;Visitez la boutique&#8221; _builder_version=&#8221;4.13.1&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#00a88d&#8221; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin_phone=&#8221;||60px||false|false&#8221; custom_margin_last_edited=&#8221;off|tablet&#8221; custom_padding=&#8221;18px|0px|18px|0px|true|true&#8221; custom_padding_tablet=&#8221;14px||14px||true|true&#8221; custom_padding_phone=&#8221;12px||12px||true|true&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; button_text_size_tablet=&#8221;14px&#8221; button_text_size_phone=&#8221;12px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;2px&#8221; box_shadow_color=&#8221;#00a88d&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#ffffff&#8221; box_shadow_color__hover_enabled=&#8221;off|hover&#8221; box_shadow_color__hover=&#8221;#e14a00&#8243;][\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/higeacbd.com\/fr\/boutique\/huiles&#8221; button_text=&#8221;Huiles&#8221; _builder_version=&#8221;4.13.1&#8243; _dynamic_attributes=&#8221;button_url&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#00a88d&#8221; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin_phone=&#8221;||60px||false|false&#8221; custom_margin_last_edited=&#8221;off|tablet&#8221; custom_padding=&#8221;1px|0px|1px|0px|true|true&#8221; custom_padding_tablet=&#8221;14px||14px||true|true&#8221; custom_padding_phone=&#8221;1px||1px||true|true&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; button_text_size_tablet=&#8221;14px&#8221; button_text_size_phone=&#8221;12px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;2px&#8221; box_shadow_color=&#8221;#00a88d&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#ffffff&#8221; box_shadow_color__hover_enabled=&#8221;off|hover&#8221; box_shadow_color__hover=&#8221;#e14a00&#8243;][\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/higeacbd.com\/fr\/boutique\/cremes&#8221; button_text=&#8221;Cr\u00e8mes&#8221; _builder_version=&#8221;4.13.1&#8243; _dynamic_attributes=&#8221;button_url&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#00a88d&#8221; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin_phone=&#8221;||60px||false|false&#8221; custom_margin_last_edited=&#8221;off|tablet&#8221; custom_padding=&#8221;1px|0px|1px|0px|true|true&#8221; custom_padding_tablet=&#8221;14px||14px||true|true&#8221; custom_padding_phone=&#8221;1px||1px||true|true&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; button_text_size_tablet=&#8221;14px&#8221; button_text_size_phone=&#8221;12px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;2px&#8221; box_shadow_color=&#8221;#00a88d&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#ffffff&#8221; box_shadow_color__hover_enabled=&#8221;off|hover&#8221; box_shadow_color__hover=&#8221;#e14a00&#8243;][\/et_pb_button][et_pb_blurb title=&#8221;Mon compte&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE0In19@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Plan de convivialit\u00e9&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NjE0In19@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Vente en gros CBD&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjUyMDEifX0=@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Vendredi noir&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEyODY0In19@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#00205c&#8221; custom_padding=&#8221;4%|5%|4%|4%|true|false&#8221; custom_padding_tablet=&#8221;50px|30px|50px|30px|true|true&#8221; custom_padding_phone=&#8221;30px|20px|30px|20px|true|true&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.5.1&#8243; text_font=&#8221;Montserrat|800|||||||&#8221; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.2em&#8221; link_text_color=&#8221;#000000&#8243; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;#96bf00&#8243; header_3_font_size=&#8221;16px&#8221; header_3_letter_spacing=&#8221;2px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_4_font=&#8221;|700||on|||||&#8221; header_4_text_color=&#8221;#ffffff&#8221; header_4_font_size=&#8221;14px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;10px||10px||true|false&#8221; text_font_size_tablet=&#8221;22px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;14px&#8221; header_3_font_size_phone=&#8221;12px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Guides<\/h4>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/spice-shop-07-2.png&#8221; alt=&#8221;simboolo higea&#8221; title_text=&#8221;spice-shop-07&#8243; _builder_version=&#8221;4.5.1&#8243; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_blurb title=&#8221;Combattre l&#039;anxi\u00e9t\u00e9&#8221; url=&#8221;https:\/\/higeacbd.com\/fr\/combattre-lanxiete&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Comment prendre de l\u2019huile de CBD&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjUzMiJ9fQ==@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Qu\u2019est-ce que la CDB&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjU4NyJ9fQ==@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Avantages cbd&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY1OSJ9fQ==@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;CBD et CBDA&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE5NjgifX0=@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Meilleur CBD&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIxNDgifX0=@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;\u00c9tudes scientifiques&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjI1MTgifX0=@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Antid\u00e9presseurs&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjM3MTQxIn19@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.5.1&#8243; background_color=&#8221;#00a88d&#8221; custom_padding=&#8221;4%|5%|4%|4%|true|false&#8221; custom_padding_tablet=&#8221;50px|30px|50px|30px|true|true&#8221; custom_padding_phone=&#8221;30px|20px|30px|20px|true|true&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.5.1&#8243; text_font=&#8221;Montserrat|800|||||||&#8221; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.2em&#8221; link_text_color=&#8221;#000000&#8243; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;#96bf00&#8243; header_3_font_size=&#8221;16px&#8221; header_3_letter_spacing=&#8221;2px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_4_font=&#8221;|700||on|||||&#8221; header_4_text_color=&#8221;#ffffff&#8221; header_4_font_size=&#8221;14px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;10px||10px||true|false&#8221; text_font_size_tablet=&#8221;22px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;14px&#8221; header_3_font_size_phone=&#8221;12px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>En savoir plus<\/h4>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/spice-shop-07-2.png&#8221; alt=&#8221;simboolo higea&#8221; title_text=&#8221;spice-shop-07&#8243; _builder_version=&#8221;4.5.1&#8243; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_blurb title=&#8221;Blog&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijc3NyJ9fQ==@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Animaux de compagnie CBD&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4OTgifX0=@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Cytokines&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE5OTkifX0=@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Terp\u00e8nes&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjI3NDEifX0=@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Extraction de CBD&#8221; url=&#8221;https:\/\/higeacbd.com\/fr\/huiles\/methodes-dextraction-de-cbd&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Huiles porteuses&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIzNzcifX0=@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Qu\u2019est-ce que les flavono\u00efdes&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIyOTMifX0=@&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; _dynamic_attributes=&#8221;url&#8221; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.4.9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.4.4&#8243; background_color=&#8221;#ffffff&#8221; custom_padding=&#8221;80px|60px|80px|60px|true|true&#8221; custom_padding_tablet=&#8221;50px|30px|50px|30px|true|true&#8221; custom_padding_phone=&#8221;30px|20px|30px|20px|true|true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.5.1&#8243; text_font=&#8221;Montserrat|800|||||||&#8221; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.2em&#8221; link_text_color=&#8221;#000000&#8243; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;#000000&#8243; header_3_font_size=&#8221;16px&#8221; header_3_letter_spacing=&#8221;2px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_4_font=&#8221;|700|||||||&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;10px||10px||true|false&#8221; text_font_size_tablet=&#8221;22px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;14px&#8221; header_3_font_size_phone=&#8221;12px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Avis juridique et politique de confidentialit\u00e9<\/h4>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/spice-shop-32-1-1.png&#8221; alt=&#8221;simboolo higea&#8221; title_text=&#8221;simboolo higea&#8221; _builder_version=&#8221;4.5.1&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_blurb url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#000000&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#000000&#8243; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; link_option_url_new_window=&#8221;on&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/higeacbd.com\/fr\/avertissement-et-conditions-generales\" target=\"_blank\" rel=\"noopener nofollow\">AVIS JURIDIQUE<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#000000&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#000000&#8243; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; link_option_url_new_window=&#8221;on&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"https:\/\/higeacbd.com\/fr\/politique-de-confidentialite-et-avis-de-cookie\" target=\"_blank\" rel=\"noopener nofollow\">CONFIDENTIALIT\u00c9 ET COOKIES<\/a>[\/et_pb_blurb][et_pb_blurb url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#000000&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#000000&#8243; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; link_option_url_new_window=&#8221;on&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/higeacbd.com\/fr\/strategie-de-retour\" target=\"_blank\" rel=\"noopener nofollow\">POLITIQUE DE RETOUR<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x56;||divi||400&#8243; icon_color=&#8221;#000000&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.13.0&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font=&#8221;|700||on|||||&#8221; body_text_color=&#8221;#000000&#8243; body_font_size=&#8221;16px&#8221; body_letter_spacing=&#8221;2px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; link_option_url_new_window=&#8221;on&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;14px&#8221; body_font_size_phone=&#8221;12px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"https:\/\/higeacbd.com\/fr\/contact\" target=\"_blank\" rel=\"noopener nofollow\">CONTACT<\/a>[\/et_pb_blurb][et_pb_text _builder_version=&#8221;4.6.5&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;15px&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"mailto:pedidos@higeacbd.com\" target=\"_blank\" rel=\"noopener noreferrer\">pedidos@higeacbd.com<\/a>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/08\/formas-de-pago.png&#8221; alt=&#8221;m\u00e9thodes de paiement&#8221; title_text=&#8221;m\u00e9thodes de paiement&#8221; _builder_version=&#8221;4.6.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;DMCA protected&#8221; _builder_version=&#8221;4.6.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<a class=\"dmca-badge\" title=\"DMCA.com Protection Status\" href=\"\/\/www.dmca.com\/Protection\/Status.aspx?ID=37f6abc2-0844-410b-a38d-d85baad73cd7\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"> <img decoding=\"async\" src=\"https:\/\/images.dmca.com\/Badges\/dmca-badge-w100-5x1-08.png?ID=31a4e9f1-3968-4406-87bf-94d2c83a66b1\" alt=\"DMCA.com Protection Status\"><\/a><\/p>\n<p><script src=\"https:\/\/images.dmca.com\/Badges\/DMCABadgeHelper.min.js\">\/\/ <![CDATA[ \/\/ ]]><\/script>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.4.4&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_signup mailchimp_list=&#8221;higeacbd|5b4d14cf0e&#8221; first_name_field=&#8221;off&#8221; last_name_field=&#8221;off&#8221; title=&#8221;Abonnez-vous et b\u00e9n\u00e9ficiez d\u2019une r\u00e9duction de 10%&#8221; _builder_version=&#8221;4.8.1&#8243; header_level=&#8221;h4&#8243; header_font=&#8221;|800|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.2em&#8221; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#00a88d&#8221; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; button_custom_padding=&#8221;18px|0px|18px|0px|true|true&#8221; button_custom_padding_tablet=&#8221;14px||14px||true|true&#8221; button_custom_padding_phone=&#8221;12px||12px||true|true&#8221; button_custom_padding_last_edited=&#8221;on|phone&#8221; background_layout=&#8221;light&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; button_text_size_tablet=&#8221;14px&#8221; button_text_size_phone=&#8221;12px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; box_shadow_style_button=&#8221;preset4&#8243; box_shadow_horizontal_button=&#8221;0px&#8221; box_shadow_vertical_button=&#8221;2px&#8221; box_shadow_color_button=&#8221;#00a88d&#8221; global_colors_info=&#8221;{}&#8221; button_text_color__hover=&#8221;#28221d&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color_button__hover=&#8221;#000000&#8243; box_shadow_color_button__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_signup][et_pb_text _builder_version=&#8221;4.6.0&#8243; text_font=&#8221;Montserrat|800|||||||&#8221; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.2em&#8221; link_text_color=&#8221;#000000&#8243; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;#000000&#8243; header_3_font_size=&#8221;16px&#8221; header_3_letter_spacing=&#8221;2px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_4_font=&#8221;|700|||||||&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;10px||10px||true|false&#8221; text_font_size_tablet=&#8221;22px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;14px&#8221; header_3_font_size_phone=&#8221;12px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Nos r\u00e9seaux sociaux<\/h4>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/spice-shop-32-1-1.png&#8221; alt=&#8221;simboolo higea&#8221; title_text=&#8221;simboolo higea&#8221; _builder_version=&#8221;4.6.0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_social_media_follow _builder_version=&#8221;4.6.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/higeacbd\/&#8221; _builder_version=&#8221;4.6.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ea2c59&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/higeacbd\/&#8221; _builder_version=&#8221;4.6.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#3b5998&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;pinterest&#8221; url=&#8221;https:\/\/www.pinterest.es\/higeacbd\/&#8221; _builder_version=&#8221;4.6.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#cb2027&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]pinterest[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;twitter&#8221; url=&#8221;https:\/\/twitter.com\/higeacbd&#8221; _builder_version=&#8221;4.6.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00aced&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]twitter[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Le syst\u00e8me endocanabino\u00efde est dans notre corps et est un ensemble de r\u00e9cepteurs qui correspondent au cannabis. Vous voulez en savoir plus?<\/p>\n","protected":false},"author":1,"featured_media":10606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[291],"tags":[],"class_list":["post-10761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-donnees"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Syst\u00e8me endocannabino\u00efde | Higea CBD<\/title>\n<meta name=\"description\" content=\"Le syst\u00e8me endocanabino\u00efde est dans notre corps et est un ensemble de r\u00e9cepteurs qui correspondent au cannabis. Vous voulez en savoir plus?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Syst\u00e8me endocannabino\u00efde | Higea CBD\" \/>\n<meta property=\"og:description\" content=\"Le syst\u00e8me endocanabino\u00efde est dans notre corps et est un ensemble de r\u00e9cepteurs qui correspondent au cannabis. Vous voulez en savoir plus?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide\" \/>\n<meta property=\"og:site_name\" content=\"Higea CBD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/higeacbd\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-14T12:55:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T12:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/sistema-endocanabinoide.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Higea CBD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@higeacbd\" \/>\n<meta name=\"twitter:site\" content=\"@higeacbd\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Higea CBD\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"60 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide\"},\"author\":{\"name\":\"Higea CBD\",\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr#\\\/schema\\\/person\\\/c26ecb4b89757dc960789de80acfc82f\"},\"headline\":\"Syst\u00e8me endocannabino\u00efde\",\"datePublished\":\"2020-09-14T12:55:54+00:00\",\"dateModified\":\"2025-03-24T12:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide\"},\"wordCount\":12155,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/higeacbd.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/sistema-endocanabinoide.jpg\",\"articleSection\":[\"Donn\u00e9es\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide\",\"url\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide\",\"name\":\"Syst\u00e8me endocannabino\u00efde | Higea CBD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/higeacbd.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/sistema-endocanabinoide.jpg\",\"datePublished\":\"2020-09-14T12:55:54+00:00\",\"dateModified\":\"2025-03-24T12:00:45+00:00\",\"description\":\"Le syst\u00e8me endocanabino\u00efde est dans notre corps et est un ensemble de r\u00e9cepteurs qui correspondent au cannabis. Vous voulez en savoir plus?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide#primaryimage\",\"url\":\"https:\\\/\\\/higeacbd.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/sistema-endocanabinoide.jpg\",\"contentUrl\":\"https:\\\/\\\/higeacbd.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/sistema-endocanabinoide.jpg\",\"width\":1000,\"height\":700,\"caption\":\"syst\u00e8me endocanabino\u00efde\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/donnees\\\/systeme-endocannabinoide#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/higeacbd.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donn\u00e9es\",\"item\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/category\\\/donnees\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Syst\u00e8me endocannabino\u00efde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr#website\",\"url\":\"https:\\\/\\\/higeacbd.com\\\/fr\",\"name\":\"Higea CBD\",\"description\":\"Comprar CBD de alta calidad\",\"publisher\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/higeacbd.com\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr#organization\",\"name\":\"Higea CBD\",\"url\":\"https:\\\/\\\/higeacbd.com\\\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/higeacbd.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-jpg.avif\",\"contentUrl\":\"https:\\\/\\\/higeacbd.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-jpg.avif\",\"width\":800,\"height\":800,\"caption\":\"Higea CBD\"},\"image\":{\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/higeacbd\",\"https:\\\/\\\/x.com\\\/higeacbd\",\"https:\\\/\\\/www.instagram.com\\\/higeacbd\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/higea-cbd\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/higeacbd\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Higa_mitologa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/higeacbd.com\\\/fr#\\\/schema\\\/person\\\/c26ecb4b89757dc960789de80acfc82f\",\"name\":\"Higea CBD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bcc9b575a49da95a71f6192ed44124452130614e0fb2f02cfbc3bb3acb34b75c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bcc9b575a49da95a71f6192ed44124452130614e0fb2f02cfbc3bb3acb34b75c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bcc9b575a49da95a71f6192ed44124452130614e0fb2f02cfbc3bb3acb34b75c?s=96&d=mm&r=g\",\"caption\":\"Higea CBD\"},\"sameAs\":[\"https:\\\/\\\/higeacbd.com\"],\"url\":\"https:\\\/\\\/higeacbd.com\\\/fr\\\/author\\\/malbersado\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Syst\u00e8me endocannabino\u00efde | Higea CBD","description":"Le syst\u00e8me endocanabino\u00efde est dans notre corps et est un ensemble de r\u00e9cepteurs qui correspondent au cannabis. Vous voulez en savoir plus?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide","og_locale":"fr_FR","og_type":"article","og_title":"Syst\u00e8me endocannabino\u00efde | Higea CBD","og_description":"Le syst\u00e8me endocanabino\u00efde est dans notre corps et est un ensemble de r\u00e9cepteurs qui correspondent au cannabis. Vous voulez en savoir plus?","og_url":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide","og_site_name":"Higea CBD","article_publisher":"https:\/\/www.facebook.com\/higeacbd","article_published_time":"2020-09-14T12:55:54+00:00","article_modified_time":"2025-03-24T12:00:45+00:00","og_image":[{"width":1000,"height":700,"url":"https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/sistema-endocanabinoide.jpg","type":"image\/jpeg"}],"author":"Higea CBD","twitter_card":"summary_large_image","twitter_creator":"@higeacbd","twitter_site":"@higeacbd","twitter_misc":{"\u00c9crit par":"Higea CBD","Dur\u00e9e de lecture estim\u00e9e":"60 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide#article","isPartOf":{"@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide"},"author":{"name":"Higea CBD","@id":"https:\/\/higeacbd.com\/fr#\/schema\/person\/c26ecb4b89757dc960789de80acfc82f"},"headline":"Syst\u00e8me endocannabino\u00efde","datePublished":"2020-09-14T12:55:54+00:00","dateModified":"2025-03-24T12:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide"},"wordCount":12155,"commentCount":0,"publisher":{"@id":"https:\/\/higeacbd.com\/fr#organization"},"image":{"@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide#primaryimage"},"thumbnailUrl":"https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/sistema-endocanabinoide.jpg","articleSection":["Donn\u00e9es"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide#respond"]}]},{"@type":"WebPage","@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide","url":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide","name":"Syst\u00e8me endocannabino\u00efde | Higea CBD","isPartOf":{"@id":"https:\/\/higeacbd.com\/fr#website"},"primaryImageOfPage":{"@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide#primaryimage"},"image":{"@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide#primaryimage"},"thumbnailUrl":"https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/sistema-endocanabinoide.jpg","datePublished":"2020-09-14T12:55:54+00:00","dateModified":"2025-03-24T12:00:45+00:00","description":"Le syst\u00e8me endocanabino\u00efde est dans notre corps et est un ensemble de r\u00e9cepteurs qui correspondent au cannabis. Vous voulez en savoir plus?","breadcrumb":{"@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide#primaryimage","url":"https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/sistema-endocanabinoide.jpg","contentUrl":"https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/09\/sistema-endocanabinoide.jpg","width":1000,"height":700,"caption":"syst\u00e8me endocanabino\u00efde"},{"@type":"BreadcrumbList","@id":"https:\/\/higeacbd.com\/fr\/donnees\/systeme-endocannabinoide#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/higeacbd.com\/fr"},{"@type":"ListItem","position":2,"name":"Donn\u00e9es","item":"https:\/\/higeacbd.com\/fr\/category\/donnees"},{"@type":"ListItem","position":3,"name":"Syst\u00e8me endocannabino\u00efde"}]},{"@type":"WebSite","@id":"https:\/\/higeacbd.com\/fr#website","url":"https:\/\/higeacbd.com\/fr","name":"Higea CBD","description":"Comprar CBD de alta calidad","publisher":{"@id":"https:\/\/higeacbd.com\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/higeacbd.com\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/higeacbd.com\/fr#organization","name":"Higea CBD","url":"https:\/\/higeacbd.com\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/higeacbd.com\/fr#\/schema\/logo\/image\/","url":"https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/logo-jpg.avif","contentUrl":"https:\/\/higeacbd.com\/wp-content\/uploads\/2020\/07\/logo-jpg.avif","width":800,"height":800,"caption":"Higea CBD"},"image":{"@id":"https:\/\/higeacbd.com\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/higeacbd","https:\/\/x.com\/higeacbd","https:\/\/www.instagram.com\/higeacbd\/","https:\/\/www.linkedin.com\/company\/higea-cbd\/","https:\/\/www.pinterest.es\/higeacbd\/","https:\/\/es.wikipedia.org\/wiki\/Higa_mitologa"]},{"@type":"Person","@id":"https:\/\/higeacbd.com\/fr#\/schema\/person\/c26ecb4b89757dc960789de80acfc82f","name":"Higea CBD","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bcc9b575a49da95a71f6192ed44124452130614e0fb2f02cfbc3bb3acb34b75c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bcc9b575a49da95a71f6192ed44124452130614e0fb2f02cfbc3bb3acb34b75c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bcc9b575a49da95a71f6192ed44124452130614e0fb2f02cfbc3bb3acb34b75c?s=96&d=mm&r=g","caption":"Higea CBD"},"sameAs":["https:\/\/higeacbd.com"],"url":"https:\/\/higeacbd.com\/fr\/author\/malbersado"}]}},"_links":{"self":[{"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/posts\/10761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/comments?post=10761"}],"version-history":[{"count":2,"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/posts\/10761\/revisions"}],"predecessor-version":[{"id":105006,"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/posts\/10761\/revisions\/105006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/media\/10606"}],"wp:attachment":[{"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/media?parent=10761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/categories?post=10761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/higeacbd.com\/fr\/wp-json\/wp\/v2\/tags?post=10761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}